{"id":476,"count":7,"description":"","link":"https:\/\/nowrebates.com\/index.php\/tag\/product-evaluations\/","name":"product evaluations","slug":"product-evaluations","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/nowrebates.com\/index.php\/wp-json\/wp\/v2\/tags\/476"}],"collection":[{"href":"https:\/\/nowrebates.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/nowrebates.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/nowrebates.com\/index.php\/wp-json\/wp\/v2\/posts?tags=476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}